{"id":5848,"date":"2025-06-09T15:35:49","date_gmt":"2025-06-09T13:35:49","guid":{"rendered":"https:\/\/aitrends.center\/protected-images-are-easier-not-more-difficult-to-steal-with-ai\/"},"modified":"2025-06-09T15:35:49","modified_gmt":"2025-06-09T13:35:49","slug":"geschutzte-bilder-sind-mit-ai-leichter-und-nicht-schwerer-zu-stehlen","status":"publish","type":"post","link":"https:\/\/aitrendscenter.eu\/de\/protected-images-are-easier-not-more-difficult-to-steal-with-ai\/","title":{"rendered":"Gesch\u00fctzte\" Bilder sind mit KI leichter, nicht schwieriger zu stehlen"},"content":{"rendered":"<p>Wir alle haben schon gesehen, wie k\u00fcnstliche Intelligenz Bilder optimieren, ver\u00e4ndern und regelrecht umgestalten kann. Das ist eine beeindruckende und bisweilen beunruhigende Demonstration ihrer Leistungsf\u00e4higkeit. Um ihre Werke vor den gestaltenden H\u00e4nden der KI zu sch\u00fctzen, greifen viele K\u00fcnstler auf Schutzma\u00dfnahmen wie <a href=\"https:\/\/arxiv.org\/pdf\/2302.06588\" target=\"_blank\" rel=\"noopener\">PhotoGuard<\/a>, <a href=\"https:\/\/arxiv.org\/pdf\/2305.12683\" target=\"_blank\" rel=\"noopener\">Nebel<\/a>und <a href=\"https:\/\/arxiv.org\/pdf\/2302.04222\" target=\"_blank\" rel=\"noopener\">Glasur<\/a>. Diese L\u00f6sungen versetzen die Bilder mit \u201eadversarialem Rauschen\u201c \u2013 geringf\u00fcgigen Ver\u00e4nderungen, die f\u00fcr das menschliche Auge unsichtbar sind, aber ausreichen, um KI-Systeme zu verwirren. Das Rauschen soll generative Modelle daran hindern, den Inhalt zu lernen oder zu ver\u00e4ndern, einschlie\u00dflich urheberrechtlich gesch\u00fctzter Bilder und Kunstwerke.<\/p>\n<p>Ironischerweise k\u00f6nnte diese Verteidigungsstrategie jedoch unbeabsichtigt den Weg f\u00fcr das Eindringen von KI geebnet haben. Ein Team von US-Forschern hat k\u00fcrzlich die Wirksamkeit von adversarial noise in Frage gestellt, und ihre Ergebnisse deuten darauf hin, dass dadurch die Bilder <em>mehr<\/em> anf\u00e4llig f\u00fcr KI-Bearbeitungen. Anhand des Stable-Diffusion-Modells als Testumgebung stellten sie fest, dass die zus\u00e4tzliche Schutzebene KI-Eingriffe nicht abwehrte \u2013 sondern sie geradezu einlud.<\/p>\n<p>Die Forscher f\u00fchrten Experimente mit einer Reihe von Kunstwerken und Fotografien durch und stellten die Widerstandsf\u00e4higkeit des adversarialen Rauschens auf die Probe, indem sie Aufgaben zur Bild-zu-Bild-Generierung und zum Stiltransfer durchf\u00fchrten. Sie verwendeten sowohl subtile als auch dramatische \u00c4nderungen, wobei sich Vorgaben wie \u201cEin junges M\u00e4dchen in einem rosa Kleid, das eine Holzh\u00fctte betritt\u201d in \u201cEin kleiner Junge in einem blauen Hemd, der ein Backsteinhaus betritt\u201d oder \u201cZwei Katzen, die auf einem Sofa faulenzen\u201d \u00e4nderten. Unabh\u00e4ngig von den Einzelheiten waren die Ergebnisse auffallend konsistent \u2013 die \u201cgesch\u00fctzten\u201d Bilder lieferten regelm\u00e4\u00dfig Ergebnisse, die den Anweisungen genauer entsprachen als ihre ungesch\u00fctzten Gegenst\u00fccke.<\/p>\n<p>Die Forscher f\u00fchren dieses unwahrscheinliche Szenario auf die Funktionsweise von Diffusionsmodellen zur\u00fcck. Diese Modelle kodieren Bilder zun\u00e4chst in einen latenten Raum, bevor sie in mehreren Schritten Rauschen einspeisen. Die Erzeugung neuer Bilder erfolgt durch Umkehrung dieses Prozesses unter Anleitung einer Textanweisung. Wird von Anfang an adversariales Rauschen eingebracht, nimmt die Unsicherheit im latenten Raum stark zu. Dies veranlasst das Modell, sich w\u00e4hrend des Rauschentfernungsprozesses st\u00e4rker auf die Textanweisung zu st\u00fctzen, was ganz unerwartet zu einem Endbild f\u00fchrt, das der Textanweisung besser entspricht.<\/p>\n<p>In ihrem Bestreben, die KI zu verwirren, scheinen die Entwickler letztendlich deren Leistung sogar verbessert zu haben. Diese unerwarteten Erkenntnisse lassen ernsthafte Zweifel an der Zuverl\u00e4ssigkeit adversarischer St\u00f6rungsmethoden als Bildschutz aufkommen und unterstreichen die Notwendigkeit von Alternativen. Ein m\u00f6glicher Kandidat ist <a href=\"https:\/\/www.linkedin.com\/help\/linkedin\/answer\/a6282984\" target=\"_blank\" rel=\"noopener\">C2PA<\/a>, ein Provenienz-Framework, das Bilder bereits bei ihrer Erstellung mit Metadaten versieht. Das sch\u00fctzt das Bild jedoch nicht <em>Inhalt<\/em>, bietet aber eine Reihe von Hinweisen, die seine Echtheit best\u00e4tigen k\u00f6nnen.<\/p>\n<p>Trotz aller Bem\u00fchungen, unsere visuellen Inhalte zu sch\u00fctzen, k\u00f6nnte die technologische Zauberei namens \u201eadversarial noise\u201c uns genau das Gegenteil von dem bieten, was wir lange Zeit f\u00fcr ihren Schutzzweck gehalten haben. Angesichts dieser neuen Erkenntnisse wird deutlich, dass wir unsere Strategie zur Bek\u00e4mpfung des Missbrauchs von KI im Bereich der visuellen Medien \u00fcberdenken m\u00fcssen. Eine ausf\u00fchrlichere Darstellung dieser faszinierenden Studie finden Sie im Originalartikel unter <a href=\"https:\/\/www.unite.ai\/protected-images-are-easier-not-more-difficult-to-steal-with-ai\/\" target=\"_blank\" rel=\"noopener\">Unite.AI<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>We&#8217;ve all seen how artificial intelligence can tweak, tinker, and outright transform images. It&#8217;s an impressive and, at times, unsettling showcase of power. In an attempt to shield their works from AI&#8217;s sculpting hands, many artists have turned to protective tools such as PhotoGuard, Mist, and Glaze. These solutions pepper the images with adversarial noise \u2013 slight alterations that are invisible to the human eye but are enough to baffle AI systems. The noise is designed to stop generative models from learning or modifying the content, including copyrighted images and artworks. However, in a twist of irony, this defense strategy [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":5849,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,47],"tags":[],"class_list":["post-5848","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ai-images","category-ai-news","post--single"],"_links":{"self":[{"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/posts\/5848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/comments?post=5848"}],"version-history":[{"count":0,"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/posts\/5848\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/media\/5849"}],"wp:attachment":[{"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/media?parent=5848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/categories?post=5848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/tags?post=5848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}