{"id":6770,"date":"2025-08-13T21:00:00","date_gmt":"2025-08-13T19:00:00","guid":{"rendered":"https:\/\/aitrends.center\/mit-researchers-develop-smarter-way-to-test-and-improve-ai-text-classifiers\/"},"modified":"2025-08-13T21:00:00","modified_gmt":"2025-08-13T19:00:00","slug":"mit-forscher-entwickeln-intelligentere-methode-zum-testen-und-verbessern-von-ki-textklassifikatoren","status":"publish","type":"post","link":"https:\/\/aitrendscenter.eu\/de\/mit-researchers-develop-smarter-way-to-test-and-improve-ai-text-classifiers\/","title":{"rendered":"MIT-Forscher entwickeln intelligentere Methode zum Testen und Verbessern von AI-Textklassifikatoren"},"content":{"rendered":"<p>Haben Sie sich schon einmal gefragt, ob die schw\u00e4rmerische Filmkritik, die Sie gerade gelesen haben, in Wirklichkeit eine mit Lob \u00fcberzogene Kritik ist? Oder ob die Antwort des Chatbots auf Ihre Frage zur Kreditkarte schon an der Grenze zur Finanzberatung liegt? Da Systeme der k\u00fcnstlichen Intelligenz (KI) immer tiefer in unser digitales \u00d6kosystem vordringen, wird die genaue Klassifizierung von Texten immer wichtiger.<\/p>\n<h3>Die Bedeutung einer genauen Textklassifizierung im Detail<\/h3>\n<p>Textklassifikatoren \u2013 Algorithmen, die darauf programmiert sind, Textinhalte zu kategorisieren \u2013 \u00fcbernehmen zunehmend Aufgaben, die traditionell von Menschen wahrgenommen wurden. Von der Sortierung von Nachrichtenbeitr\u00e4gen bis hin zur Moderation von Kundenservice-Chats: Diese KI-Systeme erkennen die Nuancen positiver oder negativer R\u00fcckmeldungen, unterscheiden Fakten von Fiktion und pr\u00fcfen sogar, ob die Antwort eines Chatbots an risikobehaftete Ratschl\u00e4ge grenzt, wie beispielsweise medizinische oder finanzielle Empfehlungen.<\/p>\n<p>Sie fragen sich, wie diese Klassifikatoren zu den richtigen Ergebnissen kommen? Ein Team am \u2019Lab for Information and Decision Systems\u201c des MIT unter der Leitung des leitenden Wissenschaftlers Kalyan Veeramachaneni machte sich daran, die Antwort darauf zu finden. Es entwickelte ein innovatives Softwarepaket, das nicht nur die Wirksamkeit dieser Klassifikatoren bewertet, sondern auch deren Genauigkeit verbessert.<\/p>\n<p>Bisher basierte die Bewertung dieser Klassifikatoren auf der Generierung synthetischer Beispiele: geringf\u00fcgig ver\u00e4nderte Versionen von S\u00e4tzen, die bereits kategorisiert wurden. Ziel ist es, zu verstehen, ob geringf\u00fcgige \u00c4nderungen, wie beispielsweise der Austausch eines Wortes, den Klassifikator ebenfalls in die Irre f\u00fchren k\u00f6nnen. Diese werden als \u201cadversarische Beispiele\u201d bezeichnet. Veeramachaneni merkt an: \u201eEs wurden verschiedene Versuche unternommen, die Schwachstellen dieser Klassifikatoren aufzudecken. Allerdings \u00fcbersehen bestehende Strategien oft entscheidende Beispiele, die als problematisch gekennzeichnet werden m\u00fcssten.\u201c<\/p>\n<h3>Eine innovative Bewertungsmethode<\/h3>\n<p>Das MIT-Team hat dieses Testverfahren verbessert, indem es gro\u00dfe Sprachmodelle (LLMs) einsetzte, um diese adversarischen Beispiele zu erstellen und zu untersuchen. Wenn zwei S\u00e4tze mit derselben Bedeutung unterschiedlich klassifiziert werden, stuft das System sie als problematisch ein. Interessanterweise kann dies in den meisten F\u00e4llen bereits durch einen einzigen Wortunterschied verursacht werden.<\/p>\n<p>Nach der Auswertung Tausender dieser Beispiele stellte das Team fest, dass ein winziger Bruchteil der W\u00f6rter \u2013 0,1% eines 30.000 W\u00f6rter umfassenden Wortschatzes \u2013 in bestimmten Anwendungsf\u00e4llen zu fast der H\u00e4lfte aller Fehler f\u00fchren k\u00f6nnte. Diese Erkenntnis erm\u00f6glichte es den Forschern, ihre Tests auf eine noch kleinere, aber umso einflussreichere Wortgruppe zu konzentrieren, wodurch das Verfahren \u00e4u\u00dferst effizient wurde.<\/p>\n<p>Bei diesem Vorhaben leistete Lei Xu, ein frisch promovierter LIDS-Doktorand, einen wesentlichen Beitrag. Xu ermittelte mithilfe fortschrittlicher Sch\u00e4tzverfahren die \u201cwirkungsvollsten\u201d W\u00f6rter, die die Entscheidung eines Klassifikators beeinflussen k\u00f6nnen. Unter Einsatz von LLMs erstellte er anschlie\u00dfend eine Hierarchie verwandter W\u00f6rter, basierend auf deren Einfluss.<\/p>\n<h3>Entwicklung von Instrumenten zur Verbesserung von KI-Klassifikatoren<\/h3>\n<p>Diese Entdeckung f\u00fchrte zu Beitr\u00e4gen, die \u00fcber reine Tests hinausgingen. Das MIT-Team entwickelte zwei Tools auf der Grundlage adversarischer Beispiele, die darauf abzielen, Klassifikatoren widerstandsf\u00e4higer zu machen und sie gegen subtile Manipulationen zu wappnen. Sie schufen \u201eSP-Attack\u201c, das adversarische S\u00e4tze generiert, und \u201eSP-Defense\u201c, das diese nutzt, um den Klassifikator neu zu trainieren und zu st\u00e4rken.<\/p>\n<p>Auch wenn die falsche Einstufung einer Filmkritik harmlos erscheinen mag, sind die Folgen in anderen Bereichen weitaus gravierender. Textklassifikatoren spielen mittlerweile eine wesentliche Rolle bei der Eind\u00e4mmung der Verbreitung von Desinformation, beim Schutz sensibler medizinischer oder finanzieller Daten und sogar bei der Unterst\u00fctzung wissenschaftlicher Forschung in Bereichen wie der Arzneimittelentwicklung und der Genomik. Daher ist eine genaue Klassifizierung wichtiger denn je.<\/p>\n<p>Um die Robustheit eines Klassifikators gegen\u00fcber Angriffen mit einzelnen W\u00f6rtern zu messen, f\u00fchrte das MIT-Team eine neue Metrik namens \u201cp\u201d ein. Ihre Methode reduzierte die Erfolgsraten adversarischer Angriffe drastisch \u2013 selbst eine geringf\u00fcgige Verbesserung wie 2% kann einen erheblichen Welleneffekt ausl\u00f6sen, wenn sie auf Milliarden von Interaktionen hochgerechnet wird.<\/p>\n<p>Die Erkenntnisse des Teams wurden in der Fachzeitschrift \u201eExpert Systems\u201c ver\u00f6ffentlicht und sind \u00f6ffentlich zug\u00e4nglich. Die Open-Source-Software erm\u00f6glicht es Entwicklern und Organisationen weltweit, zuverl\u00e4ssigere und pr\u00e4zisere KI-Systeme zu entwickeln. W\u00e4hrend wir uns gemeinsam mit der KI weiterentwickeln, werden Tools wie diese unverzichtbar sein, um sicherzustellen, dass die Inhalte, die wir lesen und auf die wir reagieren, korrekt verstanden werden \u2013 nicht nur von uns, sondern auch von KI-Systemen, die zunehmend unsere digitalen Transaktionen vermitteln.<\/p>\n<p>Wenn Sie sich n\u00e4her mit dem Thema befassen m\u00f6chten, k\u00f6nnen Sie den Originalartikel von MIT News lesen: <a href=\"https:\/\/news.mit.edu\/2025\/new-way-test-how-well-ai-systems-classify-text-0813\" target=\"_blank\" rel=\"noopener\">MIT News \u2013 Eine neue Methode, um zu testen, wie gut KI-Systeme Texte klassifizieren<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Ever wondered if the glistening movie review you just read is really a critique coated with praise? Or, if the response from the chatbot about your credit card question is on the thin line of providing financial advice? As Artificial Intelligence (AI) systems seep deeper into our digital ecosystem, the accurate classification of text has become increasingly crucial. Unpacking the Importance of Accurate Text Classification Text classifiers &#8211; algorithms pre-programmed to categorize textual content &#8211; are rapidly taking over roles traditionally played by humans. From sorting news pieces to moderating customer service chats, these AI systems determine the nuance of [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":6771,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[],"class_list":["post-6770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ai-news","post--single"],"_links":{"self":[{"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/posts\/6770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/comments?post=6770"}],"version-history":[{"count":0,"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/posts\/6770\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/media\/6771"}],"wp:attachment":[{"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/media?parent=6770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/categories?post=6770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/tags?post=6770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}