{"id":9084,"date":"2026-06-29T20:00:00","date_gmt":"2026-06-29T18:00:00","guid":{"rendered":"https:\/\/aitrendscenter.eu\/exploring-the-intersection-of-computation-and-aesthetics-a-human-centric-perspective\/"},"modified":"2026-06-29T20:00:00","modified_gmt":"2026-06-29T18:00:00","slug":"erforschung-der-schnittstelle-zwischen-informatik-und-asthetik-eine-menschenzentrierte-perspektive","status":"publish","type":"post","link":"https:\/\/aitrendscenter.eu\/de\/exploring-the-intersection-of-computation-and-aesthetics-a-human-centric-perspective\/","title":{"rendered":"Die Schnittstelle zwischen Informatik und \u00c4sthetik erkunden: Eine menschenzentrierte Perspektive"},"content":{"rendered":"<h5>\u2018Jenseits datengesteuerter \u00c4sthetik\u2019 verstehen\u2019<\/h5>\n<p>Willkommen in der Welt von \u2018Beyond Data-Driven Aesthetics\u2019. Diese einzigartige Ausstellung, die von Alexandros Haridis in der renommierten MIT Keller Gallery konzipiert wurde, l\u00e4dt Sie zu einer faszinierenden Reise ein, die zeigt, wie sich die Informatik in Bereichen wie Architektur und angewandter Kunst zu einem k\u00fcnstlerischen Ausdrucksmittel entwickelt hat. Stellen Sie sich eine lebendige Mischung aus Philosophie, Mathematik, Informatik und computergest\u00fctztem Design vor. Diese Ausstellung, die noch bis zum 30. Juni zu sehen ist, pr\u00e4sentiert die Essenz dieser Disziplinen anhand intuitiver Installationen und aufschlussreicher Visualisierungen, die komplexen Algorithmen und Systemen des maschinellen Lernens Leben einhauchen.<\/p>\n<h5>Die Inspirationsquellen hinter der Ausstellung entschl\u00fcsseln<\/h5>\n<p>Was hat Haridis also dazu bewogen, die Ausstellung \u2018Beyond Data-Driven Aesthetics\u2019 zu konzipieren? Nun, die Wurzeln der Ausstellung liegen in drei bedeutenden Forschungsbereichen. W\u00e4hrend seiner Promotion am MIT, die sich auf Design und Computerwissenschaft konzentrierte, beobachtete Haridis die sich entwickelnde Verbindung zwischen datengesteuerten Systemen des maschinellen Lernens wie ChatGPT und Stable Diffusion einerseits und Diskussionen rund um Kreativit\u00e4t und \u00e4sthetisches Urteilsverm\u00f6gen andererseits. Diese Erkenntnis unterstrich, dass viele \u2018moderne\u2019 Aspekte der KI auf bedeutende Ereignisse der Vergangenheit zur\u00fcckgehen, wie beispielsweise das Dartmouth Summer Research Project von 1956, einen Meilenstein in der Geschichte der KI-Forschung.<\/p>\n<p>Dar\u00fcber hinaus widmete sich Haridis der Forschung im Bereich des computergest\u00fctzten Designs und der Formgrammatiken und beleuchtete dabei das Zusammenspiel zwischen menschlicher Einsicht und computergest\u00fctzter Berechnung anhand regelbasierter Methoden. Unser K\u00fcnstler griff \u00e4sthetische Theorien von ikonischen Pers\u00f6nlichkeiten wie Samuel Taylor Coleridge und Oscar Wilde auf, um das Potenzial und die Grenzen aktueller digitaler Berechnungsmodelle zu hinterfragen.<\/p>\n<p>Eine weitere Inspirationsquelle ist der effektive Einsatz von Design, Umsetzung und Datenvisualisierung, um mathematische Prinzipien und Systeme des maschinellen Lernens intuitiv zu verstehen. Diese Strategien erleichtern uns das Verst\u00e4ndnis computergest\u00fctzter Systeme und \u00fcberbr\u00fccken die Kluft zwischen r\u00e4tselhaften Algorithmen und menschlicher Wahrnehmung.<\/p>\n<h5>Forschung zum Leben erwecken<\/h5>\n<p>Kunst hat die F\u00e4higkeit, komplexe Forschungskonzepte in leicht verst\u00e4ndliche visuelle Darstellungen und eindringliche Erlebnisse zu verwandeln. Haridis nutzt Methoden wie Software-Rekonstruktion und Datenvisualisierung, um schwer verst\u00e4ndliche algorithmische Konzepte in faszinierende r\u00e4umliche Erz\u00e4hlungen zu verwandeln. Die Ausstellung ist um f\u00fcnf Themen herum aufgebaut \u2013 \u00c4sthetisches Ma\u00df, \u00c4sthetische Leitlinien, Algorithmische \u00c4sthetik, \u00c4sthetische Aneignung und \u00c4sthetische Neuheit \u2013 und bietet jedem Besucher eine einzigartige Perspektive auf die computergest\u00fctzten Aspekte des \u00e4sthetischen Urteils.<\/p>\n<p>Zur Veranschaulichung: Ein Thema, \u2018Ma\u00df\u2019, befasst sich mit George Birkhoffs bahnbrechender Arbeit aus den 1930er Jahren, die darauf abzielte, \u00e4sthetischer Anziehungskraft einen numerischen Wert zuzuweisen. Das Thema \u2018Neuartigkeit\u2019 hingegen untersucht, wie das maschinelle Lernsystem AICAN Bilder auf der Grundlage kognitiver \u00c4sthetik bewertet.<\/p>\n<p>Zum Abschluss der Ausstellung \u2018Beyond Data-Driven Aesthetics\u2019 gibt uns Haridis Denkanst\u00f6\u00dfe f\u00fcr zuk\u00fcnftige Erkundungen computergest\u00fctzter Systeme im Bereich der \u00e4sthetischen Beurteilung und Transformation. Die Ausstellung wird zu einer Plattform, auf der dar\u00fcber nachgedacht werden kann, wie computergest\u00fctzte Bewertungen \u00fcber funktionale Anforderungen in Designr\u00e4umen hinausgehen, und kn\u00fcpft dabei an computergest\u00fctzte Modelle aus dem fr\u00fchen 20. Jahrhundert an. <\/p>\n<p>Haridis\u2019 Neugierde veranlasst ihn dazu, diese Konzepte in die gebaute Umwelt zu \u00fcbertragen und so Designern und Ingenieuren dabei zu helfen, zu verstehen, wie computergest\u00fctzte Verfahren die menschlichen Erfahrungen in den von ihnen genutzten R\u00e4umen bereichern k\u00f6nnen. Er geht zudem auf die Rolle des Designs als Interpretationsinstrument ein und nutzt Software-Rekonstruktion und Visualisierung, um komplexe computergest\u00fctzte Systeme verst\u00e4ndlicher zu machen.<\/p>\n<p>Besch\u00e4ftigen Sie sich doch einmal etwas eingehender mit diesem Thema, <a href=\"https:\/\/news.mit.edu\/2026\/3-questions-beyond-data-driven-aesthetics-alexandros-haridis-0629\" target=\"_blank\" rel=\"noopener\">Den Originalartikel finden Sie hier<\/a>. Nun zu einem anderen Thema: Zieht Ihr Unternehmen KI-Automatisierungsl\u00f6sungen in Betracht? Erfahren Sie, wie implementi.ai Ihnen dabei helfen kann, Ihre Prozesse zu optimieren und Ihre Gesch\u00e4ftsabl\u00e4ufe zu verbessern.<\/p>","protected":false},"excerpt":{"rendered":"<p>Understanding &#8216;Beyond Data-Driven Aesthetics&#8217; Welcome to the world of &#8216;Beyond Data-Driven Aesthetics.&#8217; This unique exhibition masterminded by Alexandros Haridis at the esteemed MIT Keller Gallery invites you to a fascinating journey showing how computing has evolved into an artistic avenue in fields like architecture and applied arts. Imagine a vivid blend of philosophy, math, computer science, and design computation. This exhibit, continuing until June 30, presents the essence of these disciplines through intuitive installations and revealing visualizations that breathe life into intricate algorithms and machine-learning systems. Unraveling the Inspirations Behind the Exhibit So, what prompted Haridis to put together &#8216;Beyond [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":9085,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,47],"tags":[],"class_list":["post-9084","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ai-automation","category-ai-news","post--single"],"_links":{"self":[{"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/posts\/9084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/comments?post=9084"}],"version-history":[{"count":0,"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/posts\/9084\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/media\/9085"}],"wp:attachment":[{"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/media?parent=9084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/categories?post=9084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aitrendscenter.eu\/de\/wp-json\/wp\/v2\/tags?post=9084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}